{"id":1440,"date":"2024-11-28T15:39:59","date_gmt":"2024-11-28T15:39:59","guid":{"rendered":"https:\/\/verdianpower.com\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/"},"modified":"2025-09-29T11:44:17","modified_gmt":"2025-09-29T11:44:17","slug":"nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference","status":"publish","type":"post","link":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/","title":{"rendered":"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE"},"content":{"rendered":"\n<p><strong>Premiata la startup con il miglior progetto nell\u2019ambito delle tecnologie energetiche pulite che verr\u00e0 supportata nel suo sviluppo da Verdian Power e Green Horse Advisory<\/strong><\/p>\n\n<p><strong>NLcomp<\/strong>, startup innovativa nata a Monfalcone (Gorizia), \u00e8 la vincitrice del contest tra le startup del cleantech organizzato per la prima edizione dell\u2019Italian <strong>Energy Tech Conference<\/strong>. Il progetto di NLcomp \u00e8 stato ritenuto il migliore nell\u2019ambito delle tecnologie energetiche pulite e sar\u00e0 supportato nel suo sviluppo da <strong>Verdian Power<\/strong> e <strong>Green Horse Advisory<\/strong>.<\/p>\n\n<p>Il progetto di NLcomp \u00e8 stato scelto tra tutti i finalisti con la seguente motivazione: \u201cNLcomp vince per l\u2019Innovazione e le molte opportunit\u00e0 di applicazione al settore della produzione di energia eolica, sia per i nuovi impianti che per il retrofit di quelli esistenti, oltre a offrire opportunit\u00e0 di monetizzazione attraverso il riciclo delle sue componenti\u201d.<\/p>\n\n<p>NLcomp, startup innovativa fondata a Monfalcone (provincia di Gorizia) ha sviluppato una tecnologia all\u2019avanguardia che punta sulla sostenibilit\u00e0 per affrontare il problema dello smaltimento delle pale eoliche. L\u2019azienda ha progettato una turbina eolica completamente riciclabile che contribuisce a ridurre l\u2019impatto ambientale del settore e a promuovere un\u2019economia circolare. Con questa soluzione, le pale delle turbine eoliche, tradizionalmente difficili da riciclare, possono essere riutilizzate e recuperate, cos\u00ec da offrire un\u2019alternativa sostenibile e innovativa per il futuro delle energie rinnovabili.<\/p>\n\n<p>La prima edizione <strong>dell\u2019Energy Tech Conference\u00a02024<\/strong> \u00e8 stata organizzata da <strong>Verdian Power<\/strong>, e da <strong>Green Horse Advisory<\/strong> per fare il punto sulle nuove tecnologie per la produzione di energie rinnovabili, un mercato estremamente dinamico e soggetto a una costante evoluzione. Nel corso dell\u2019evento sono state presentate le ultime novit\u00e0 relative al solare e alle batterie, considerati decisivi per garantire la transizione energetica.<\/p>\n\n<p><strong>Verdian Power<\/strong>, produttore indipendente di energia rinnovabile, parte del fondo infrastrutturale <strong>Nuveen Infrastructure<\/strong>, offrir\u00e0 alla startup vincitrice la possibilit\u00e0 di testare la sua tecnologia innovativa in uno dei suoi impianti di produzione di energia rinnovabile, per determinarne la fattibilit\u00e0 tecnica ed economica (il cosiddetto proof of concept).<\/p>\n\n<p><strong>Green Horse Advisory<\/strong>, realt\u00e0 di consulenza strategica specializzata esclusivamente sul settore della transizione energetica, delle energie rinnovabili e delle infrastrutture sostenibili, unisce competenze legali, finanziarie e di project development grazie alle tre societ\u00e0 da cui \u00e8 composta: <strong>Green Horse Legal Advisory, Green Horse Financial Advisory e Green Horse Engineering<\/strong>. La startup vincitrice potr\u00e0 quindi essere supportata da Green Horse Legal per la definizione degli aspetti legali relativi ai round di investimento e dei finanziamenti, da Green Horse Financial Advisory nel perfezionamento del business plan e da Green Horse Engineering per la gestione e la risoluzione di problematiche di natura tecnica.<\/p>\n\n<p>La giuria che ha assegnato il riconoscimento \u00e8 composta da:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Iacopo Magrini<\/strong>, CEO \u2013 Green Horse Engineering;<\/li>\n\n\n\n<li><strong>Luca Campaiola<\/strong>, Venture Capitalist &amp; Strategic Advisor;<\/li>\n\n\n\n<li><strong>Jordi Francesch<\/strong>, Managing Director, Global Head of Asset management \u2013 Nuveen Clean Energy Infrastructure;<\/li>\n\n\n\n<li><strong>Leonardo Massa<\/strong>, Investment Director at MITO Technology;<\/li>\n\n\n\n<li><strong>Ezio Ravaccia<\/strong>, Partner di Primo Climate;<\/li>\n\n\n\n<li><strong>Stefano Soliano<\/strong>, CEO \u2013 C.NEXT SpA Societ\u00e0 Benefit, Vice President \u2013 InnovUp Italian Innovation &amp; Startup Ecosystem.<\/li>\n<\/ul>\n\n<p><i>\u201cSiamo davvero soddisfatti della partecipazione di numerose startup a questo primo evento a loro dedicato \u2013<\/i>\u00a0ha dichiarato\u00a0<b>Iacopo Magrini<\/b>, CEO di Green Horse Engineering.<br\/><br\/><i>&#8220;Ci ha sorpreso la qualit\u00e0 delle iniziative tanto che formare la classifica non \u00e8 stato semplice. Abbiamo cercato di valutare gli aspetti non solo tecnici ma anche di un possibile sbocco commerciale dei loro progetti e proprio con questa finalit\u00e0 potranno usufruire delle competenze delle varie anime di Green Horse Advisory per facilitare il difficile cammino verso una commercializzazione dei loro progetti\u201d.<\/i><\/p>\n\n<p>Le startup finaliste hanno presentato progetti e proposte innovative nell\u2019ambito delle tecnologie energetiche pulite. Oltre alla vincitrice NLcomp, la giuria ha valutato una shortlist di altre cinque startup finaliste che nel corso dell\u2019evento hanno presentato ai fondi di investimento e ai player della transizione green le loro tecnologie innovative. Le altre cinque startup finaliste sono state Deentra, FlashTube, i-TES, KEW Technology e WPE Research &amp; Development.<\/p>\n\n<p>Progetti finalisti<\/p>\n\n<p> <\/p>\n\n<ul class=\"wp-block-list\">\n<li><b>Deentra<\/b>\u00a0ha sede a San Donato Milanese e ha sviluppato una piattaforma che consente a privati di acquistare un pannello fotovoltaico e di installarlo sul tetto di un\u2019azienda. Le aziende possono beneficiare dell\u2019energia prodotta a una tariffa competitiva senza alcun investimento iniziale, mentre i proprietari dei pannelli ricevono\u00a0un canone di noleggio basato sull\u2019energia prodotta dai\u00a0loro\u00a0pannelli.<\/li>\n\n\n\n<li><b>FlashTube<\/b>\u00a0\u00e8 una startup nata all\u2019interno del Tecnopolo di Rimini dell\u2019Alma Mater Studiorum (Universit\u00e0 di Bologna) ed \u00e8 focalizzata sullo sviluppo e la commercializzazione di celle a combustibile basate su tecnologie brevettate che trasformano i rifiuti organici, come residui alimentari e agricoli, in energia pulita. Il processo non solo genera elettricit\u00e0, ma produce anche fertilizzante liquido come sottoprodotto, soddisfacendo cos\u00ec sia esigenze energetiche che agricole. Questa tecnologia si differenzia dalle tradizionali soluzioni di bioenergia perch\u00e9 elimina la necessit\u00e0 di organismi viventi, aumentando l\u2019efficienza e l\u2019affidabilit\u00e0.<\/li>\n\n\n\n<li><b>i-TES<\/b>, nata a Torino e dal 2016 startup innovativa, sviluppa e perfeziona batterie termiche innovative e impianti di accumulo termico attraverso l\u2019utilizzo di materiali a cambio di fase. I materiali a cambio di fase sono in grado di assorbire e rilasciare grandi quantit\u00e0 di calore quando passano da uno stato fisico all\u2019altro. i-TES ha ideato le batterie termiche sfruttando questa propriet\u00e0. A differenza delle altre batterie, quelle di i-TES alla modalit\u00e0 di carica classica come quella elettrica, aggiungono la carica diretta con gas a pompa di calore che riduce al minimo le perdite durante il processo di ricarica.<\/li>\n\n\n\n<li><b>KEW Technology<\/b>, azienda di soluzioni energetiche sostenibili con sede nel Regno Unito, ha sviluppato una tecnologia che trasforma in modo efficiente tutti i tipi di risorse non riciclabili e biomassa di bassa qualit\u00e0 in un portafoglio di gas di sintesi (monossido di carbonio, idrogeno, metano e anidride carbonica) e combustibili a basse emissioni di carbonio per l\u2019applicazione in settori energetici difficili da decarbonizzare.<\/li>\n\n\n\n<li><b>WPE Research &amp; Development\u00a0<\/b>\u00e8 stata fondata a Padova nel 2019. La societ\u00e0 ha creato EOS Turbowind, una microturbina eolica che integra in modo intelligente varie tecnologie per massimizzare l\u2019energia eolica in vari contesti, con un\u2019attenzione particolare agli ambienti urbani. La microturbina aiuta attivamente privati e aziende a ridurre i costi dei consumi energetici e ad accelerare la loro transizione verso un\u2019energia sostenibile. WPE incorpora algoritmi predittivi basati sull\u2019intelligenza artificiale, che monitorano e regolano la produzione di energia in tempo reale in base alle condizioni ambientali e alla domanda, garantendo prestazioni ottimali, efficienza energetica e manutenzione proattiva.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Premiata la startup con il miglior progetto nell\u2019ambito delle tecnologie energetiche pulite che verr\u00e0 supportata nel suo sviluppo da Verdian Power e Green Horse Advisory NLcomp, startup innovativa nata a Monfalcone (Gorizia), \u00e8 la vincitrice del contest tra le startup del cleantech organizzato per la prima edizione dell\u2019Italian Energy Tech Conference. Il progetto di NLcomp [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicato-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE - DEV VERDIAN<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE - DEV VERDIAN\" \/>\n<meta property=\"og:description\" content=\"Premiata la startup con il miglior progetto nell\u2019ambito delle tecnologie energetiche pulite che verr\u00e0 supportata nel suo sviluppo da Verdian Power e Green Horse Advisory NLcomp, startup innovativa nata a Monfalcone (Gorizia), \u00e8 la vincitrice del contest tra le startup del cleantech organizzato per la prima edizione dell\u2019Italian Energy Tech Conference. Il progetto di NLcomp [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/\" \/>\n<meta property=\"og:site_name\" content=\"DEV VERDIAN\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T15:39:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-29T11:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wilfrido\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wilfrido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/\"},\"author\":{\"name\":\"Wilfrido\",\"@id\":\"https:\/\/dev.verdianpower.com\/it\/#\/schema\/person\/0c403934a6ee484f6d4b073fc2c0f53d\"},\"headline\":\"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE\",\"datePublished\":\"2024-11-28T15:39:59+00:00\",\"dateModified\":\"2025-09-29T11:44:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/\"},\"wordCount\":1070,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg\",\"articleSection\":[\"Comunicato stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/\",\"url\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/\",\"name\":\"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE - DEV VERDIAN\",\"isPartOf\":{\"@id\":\"https:\/\/dev.verdianpower.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg\",\"datePublished\":\"2024-11-28T15:39:59+00:00\",\"dateModified\":\"2025-09-29T11:44:17+00:00\",\"author\":{\"@id\":\"https:\/\/dev.verdianpower.com\/it\/#\/schema\/person\/0c403934a6ee484f6d4b073fc2c0f53d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#primaryimage\",\"url\":\"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg\",\"contentUrl\":\"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg\",\"width\":1340,\"height\":701,\"caption\":\"2024-11-27 ITALIAN ENERGY TECH CONFERENCE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.verdianpower.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.verdianpower.com\/it\/#website\",\"url\":\"https:\/\/dev.verdianpower.com\/it\/\",\"name\":\"DEV VERDIAN\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.verdianpower.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.verdianpower.com\/it\/#\/schema\/person\/0c403934a6ee484f6d4b073fc2c0f53d\",\"name\":\"Wilfrido\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev.verdianpower.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a50d3f73478502cff84b5f8a95a30c305ddf2e154b47d784044fa79487d2bee2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a50d3f73478502cff84b5f8a95a30c305ddf2e154b47d784044fa79487d2bee2?s=96&d=mm&r=g\",\"caption\":\"Wilfrido\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE - DEV VERDIAN","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE - DEV VERDIAN","og_description":"Premiata la startup con il miglior progetto nell\u2019ambito delle tecnologie energetiche pulite che verr\u00e0 supportata nel suo sviluppo da Verdian Power e Green Horse Advisory NLcomp, startup innovativa nata a Monfalcone (Gorizia), \u00e8 la vincitrice del contest tra le startup del cleantech organizzato per la prima edizione dell\u2019Italian Energy Tech Conference. Il progetto di NLcomp [&hellip;]","og_url":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/","og_site_name":"DEV VERDIAN","article_published_time":"2024-11-28T15:39:59+00:00","article_modified_time":"2025-09-29T11:44:17+00:00","og_image":[{"width":1340,"height":701,"url":"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg","type":"image\/jpeg"}],"author":"Wilfrido","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Wilfrido","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#article","isPartOf":{"@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/"},"author":{"name":"Wilfrido","@id":"https:\/\/dev.verdianpower.com\/it\/#\/schema\/person\/0c403934a6ee484f6d4b073fc2c0f53d"},"headline":"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE","datePublished":"2024-11-28T15:39:59+00:00","dateModified":"2025-09-29T11:44:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/"},"wordCount":1070,"commentCount":0,"image":{"@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg","articleSection":["Comunicato stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/","url":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/","name":"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE - DEV VERDIAN","isPartOf":{"@id":"https:\/\/dev.verdianpower.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#primaryimage"},"image":{"@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg","datePublished":"2024-11-28T15:39:59+00:00","dateModified":"2025-09-29T11:44:17+00:00","author":{"@id":"https:\/\/dev.verdianpower.com\/it\/#\/schema\/person\/0c403934a6ee484f6d4b073fc2c0f53d"},"breadcrumb":{"@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#primaryimage","url":"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg","contentUrl":"https:\/\/dev.verdianpower.com\/wp-content\/uploads\/2025\/09\/LPA-12-1340x701-1.jpg","width":1340,"height":701,"caption":"2024-11-27 ITALIAN ENERGY TECH CONFERENCE"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.verdianpower.com\/it\/nlcomp-vince-il-cleantech-startup-contest-della-prima-edizione-dellitalian-energy-tech-conference\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.verdianpower.com\/it\/"},{"@type":"ListItem","position":2,"name":"NLCOMP VINCE IL CLEANTECH STARTUP CONTEST DELLA PRIMA EDIZIONE DELL\u2019ITALIAN ENERGY TECH CONFERENCE"}]},{"@type":"WebSite","@id":"https:\/\/dev.verdianpower.com\/it\/#website","url":"https:\/\/dev.verdianpower.com\/it\/","name":"DEV VERDIAN","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.verdianpower.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/dev.verdianpower.com\/it\/#\/schema\/person\/0c403934a6ee484f6d4b073fc2c0f53d","name":"Wilfrido","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev.verdianpower.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a50d3f73478502cff84b5f8a95a30c305ddf2e154b47d784044fa79487d2bee2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a50d3f73478502cff84b5f8a95a30c305ddf2e154b47d784044fa79487d2bee2?s=96&d=mm&r=g","caption":"Wilfrido"}}]}},"_links":{"self":[{"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/posts\/1440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/comments?post=1440"}],"version-history":[{"count":0,"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/posts\/1440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/media\/923"}],"wp:attachment":[{"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/media?parent=1440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/categories?post=1440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.verdianpower.com\/it\/wp-json\/wp\/v2\/tags?post=1440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}